{"id":5508,"date":"2025-04-29T14:29:09","date_gmt":"2025-04-29T18:29:09","guid":{"rendered":"https:\/\/aquaspa1.wpenginepowered.com\/?page_id=5508"},"modified":"2026-07-10T10:01:18","modified_gmt":"2026-07-10T14:01:18","slug":"maquillage","status":"publish","type":"page","link":"https:\/\/aquaspalg.com\/fr\/services\/maquillage\/","title":{"rendered":"Maquillage"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb admin_label=\u00a0\u00bbSection\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/aquaspalg.com\/wp-content\/uploads\/2022\/06\/header-home.jpg\u00a0\u00bb background_size=\u00a0\u00bbcustom\u00a0\u00bb background_image_width=\u00a0\u00bb90%\u00a0\u00bb height=\u00a0\u00bb80vh\u00a0\u00bb custom_padding=\u00a0\u00bb170px|60px|150px|60px|false|true\u00a0\u00bb bottom_divider_height=\u00a0\u00bb35px\u00a0\u00bb bottom_divider_repeat=\u00a0\u00bb1x\u00a0\u00bb bottom_divider_flip=\u00a0\u00bbvertical\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb60px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb78px\u00a0\u00bb header_font=\u00a0\u00bbCervo medium|||on|||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb50px\u00a0\u00bb custom_padding=\u00a0\u00bb130px||||false|false\u00a0\u00bb custom_css_main_element=\u00a0\u00bbtext-shadow: 2px 2px 0 rgb(0 0 0 \/ 8%);\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>MASSAGES<\/h1>\n<p>[\/et_pb_text][et_pb_divider color=\u00a0\u00bb#FFFFFF\u00a0\u00bb divider_weight=\u00a0\u00bb4px\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb100px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb140px||0px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb90px||0px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb90px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/aquaspalg.com\/wp-content\/uploads\/2025\/04\/2148301847.jpg\u00a0\u00bb height=\u00a0\u00bb480px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb78px\u00a0\u00bb header_font=\u00a0\u00bbCervo medium|||on|||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb50px\u00a0\u00bb custom_padding=\u00a0\u00bb180px||100px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb100px||100px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb100px||100px||false|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb50px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb46px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbtext-shadow: 2px 2px 0 rgb(0 0 0 \/ 8%);\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>MAQUILLAGE<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbNails\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#fcfcfc\u00a0\u00bb background_enable_image=\u00a0\u00bboff\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbbottom_left\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; admin_label=\u00a0\u00bbRow\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb1440px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbSignature Aqua Spa Facial\t\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|||on|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>YEUX SEULEMENT<\/h2>\n<p class=\"sb-cost\">$70<\/p>\n<p><span style=\"font-weight: 400;\">Il s\u2019agit d\u2019un maquillage express qui se concentre uniquement sur les yeux et les sourcils, pour les faire ressortir et les rendre plus visibles, tout en donnant une impression d\u2019audace et de d\u00e9finition.\u00a0<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbGrowth Factors Treatment \u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|||on|||||\u00a0\u00bb header_6_font=\u00a0\u00bb|||on|||||\u00a0\u00bb header_6_font_size=\u00a0\u00bb36px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 class=\"h4\">MAQUILLAGE GLAM COMPLET\u00a0<b><br \/><\/b><\/h2>\n<p>$115<\/p>\n<p><span style=\"font-weight: 400;\">Le maquillage glam est un maquillage audacieux, dramatique et impeccable qui fait sensation. Il est parfait pour les \u00e9v\u00e9nements tels que les bals de fin d&rsquo;ann\u00e9e, les f\u00eates de mariage, les galas, les s\u00e9ances photo ou les soir\u00e9es o\u00f9 l&rsquo;on veut aller jusqu&rsquo;au bout de son maquillage.\u00a0<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb1440px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbMulti-Peel Treatment\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|||on|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>SOFT GLAM<\/h2>\n<p class=\"sb-cost\">$100<\/p>\n<p><span style=\"font-weight: 400;\">Il s&rsquo;agit d&rsquo;une version plus douce, plus soign\u00e9e et plus naturelle du glamour int\u00e9gral. Il s&rsquo;agit d&rsquo;un style de maquillage qui rehausse les traits avec des \u00e9l\u00e9ments subtils et m\u00e9lang\u00e9s, en utilisant des tons neutres et chauds, et une touche de brillance, ce qui donne un fini frais et ros\u00e9. Ce style est id\u00e9al pour un \u00e9v\u00e9nement jour\/nuit et pour les personnes qui n&rsquo;aiment pas les maquillages trop lourds.\u00a0<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbRevealing Treatment\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|||on|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>BRIDAL<\/h2>\n<p class=\"sb-cost\">$150 &#8211; $175<\/p>\n<p><span style=\"font-weight: 400;\">Le maquillage de mari\u00e9e a pour but de mettre en valeur la beaut\u00e9 naturelle de la mari\u00e9e, en s&rsquo;assurant qu&rsquo;elle soit \u00e0 son meilleur pour ce jour sp\u00e9cial, tout en supportant de longues heures de travail, de photos et d&rsquo;\u00e9motions. Cela comprend un maquillage complet du visage avec un contour et l&rsquo;ajout d&rsquo;une touche personnelle, afin de cr\u00e9er un look impeccable et durable. <\/span><span style=\"font-weight: 400;\">Un essai de maquillage est recommand\u00e9 pour les mari\u00e9es.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb1440px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbBalancing Treatment\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|||on|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>ESSAI<\/h2>\n<p class=\"sb-cost\">$80<\/p>\n<p><span style=\"font-weight: 400;\">Un essai de maquillage est fortement recommand\u00e9 et constitue une partie cruciale de la pr\u00e9paration d&rsquo;un mariage ou d&rsquo;une occasion sp\u00e9ciale. Cet essai vous permettra de vous sentir pleinement \u00e0 l&rsquo;aise et en confiance avec les r\u00e9sultats. L&rsquo;essai vous permet de discuter de vos pr\u00e9occupations ou de vos pr\u00e9f\u00e9rences, et de vous assurer que l&rsquo;artiste comprend votre vision et le look souhait\u00e9.\u00a0 Notre objectif est que vous repartiez heureuse et rayonnante avec le maquillage final pour le grand jour.\u00a0<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbActive Repair Treatment \u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bb|||on|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>LASHES ADD ON<\/h2>\n<p class=\"sb-cost\">$10 &#8211; $15<\/p>\n<p><span style=\"font-weight: 400;\">Les cils ajouteront de l&#8217;emphase aux yeux et finiront le look. Cette option est sugg\u00e9r\u00e9e pour les \u00e9v\u00e9nements sp\u00e9ciaux qui n\u00e9cessitent des photos. <\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MASSAGESMAQUILLAGEYEUX SEULEMENT $70 Il s\u2019agit d\u2019un maquillage express qui se concentre uniquement sur les yeux et les sourcils, pour les faire ressortir et les rendre plus visibles, tout en donnant une impression d\u2019audace et de d\u00e9finition.\u00a0MAQUILLAGE GLAM COMPLET\u00a0 $115 Le maquillage glam est un maquillage audacieux, dramatique et impeccable qui fait sensation. Il est parfait [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":1033,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-5508","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Services de Maquillage \u00e0 l\u2019Ouest-de-l\u2019\u00cele | AquaSpa Nuance<\/title>\n<meta name=\"description\" content=\"Services de maquillage professionnel chez AquaSpa Nuance \u00e0 Dollard-Des-Ormeaux. Maquillage pour \u00e9v\u00e9nements et mariage dans l\u2019Ouest-de-l\u2019\u00cele.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Services de Maquillage \u00e0 l\u2019Ouest-de-l\u2019\u00cele | AquaSpa Nuance\" \/>\n<meta property=\"og:description\" content=\"Services de maquillage professionnel chez AquaSpa Nuance \u00e0 Dollard-Des-Ormeaux. Maquillage pour \u00e9v\u00e9nements et mariage dans l\u2019Ouest-de-l\u2019\u00cele.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquaspalg.com\/fr\/services\/maquillage\/\" \/>\n<meta property=\"og:site_name\" content=\"Aqua Spa Lyne Giroux\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aquaspalynegiroux\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T14:01:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aquaspalg.com\/wp-content\/uploads\/2025\/01\/Aqua-Spa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aquaspalg.com\\\/fr\\\/services\\\/maquillage\\\/\",\"url\":\"https:\\\/\\\/aquaspalg.com\\\/fr\\\/services\\\/maquillage\\\/\",\"name\":\"Services de Maquillage \u00e0 l\u2019Ouest-de-l\u2019\u00cele | AquaSpa Nuance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aquaspalg.com\\\/fr\\\/#website\"},\"datePublished\":\"2025-04-29T18:29:09+00:00\",\"dateModified\":\"2026-07-10T14:01:18+00:00\",\"description\":\"Services de maquillage professionnel chez AquaSpa Nuance \u00e0 Dollard-Des-Ormeaux. Maquillage pour \u00e9v\u00e9nements et mariage dans l\u2019Ouest-de-l\u2019\u00cele.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aquaspalg.com\\\/fr\\\/services\\\/maquillage\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aquaspalg.com\\\/fr\\\/services\\\/maquillage\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aquaspalg.com\\\/fr\\\/services\\\/maquillage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aquaspalg.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/aquaspalg.com\\\/fr\\\/services\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maquillage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aquaspalg.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/aquaspalg.com\\\/fr\\\/\",\"name\":\"Aqua Spa Lyne Giroux\",\"description\":\"A unique experience in Montreal\u2019s West Island.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aquaspalg.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Services de Maquillage \u00e0 l\u2019Ouest-de-l\u2019\u00cele | AquaSpa Nuance","description":"Services de maquillage professionnel chez AquaSpa Nuance \u00e0 Dollard-Des-Ormeaux. Maquillage pour \u00e9v\u00e9nements et mariage dans l\u2019Ouest-de-l\u2019\u00cele.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_CA","og_type":"article","og_title":"Services de Maquillage \u00e0 l\u2019Ouest-de-l\u2019\u00cele | AquaSpa Nuance","og_description":"Services de maquillage professionnel chez AquaSpa Nuance \u00e0 Dollard-Des-Ormeaux. Maquillage pour \u00e9v\u00e9nements et mariage dans l\u2019Ouest-de-l\u2019\u00cele.","og_url":"https:\/\/aquaspalg.com\/fr\/services\/maquillage\/","og_site_name":"Aqua Spa Lyne Giroux","article_publisher":"https:\/\/www.facebook.com\/aquaspalynegiroux\/","article_modified_time":"2026-07-10T14:01:18+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/aquaspalg.com\/wp-content\/uploads\/2025\/01\/Aqua-Spa.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aquaspalg.com\/fr\/services\/maquillage\/","url":"https:\/\/aquaspalg.com\/fr\/services\/maquillage\/","name":"Services de Maquillage \u00e0 l\u2019Ouest-de-l\u2019\u00cele | AquaSpa Nuance","isPartOf":{"@id":"https:\/\/aquaspalg.com\/fr\/#website"},"datePublished":"2025-04-29T18:29:09+00:00","dateModified":"2026-07-10T14:01:18+00:00","description":"Services de maquillage professionnel chez AquaSpa Nuance \u00e0 Dollard-Des-Ormeaux. Maquillage pour \u00e9v\u00e9nements et mariage dans l\u2019Ouest-de-l\u2019\u00cele.","breadcrumb":{"@id":"https:\/\/aquaspalg.com\/fr\/services\/maquillage\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aquaspalg.com\/fr\/services\/maquillage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aquaspalg.com\/fr\/services\/maquillage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aquaspalg.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/aquaspalg.com\/fr\/services\/"},{"@type":"ListItem","position":3,"name":"Maquillage"}]},{"@type":"WebSite","@id":"https:\/\/aquaspalg.com\/fr\/#website","url":"https:\/\/aquaspalg.com\/fr\/","name":"Aqua Spa Lyne Giroux","description":"A unique experience in Montreal\u2019s West Island.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aquaspalg.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/aquaspalg.com\/fr\/wp-json\/wp\/v2\/pages\/5508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquaspalg.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aquaspalg.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aquaspalg.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/aquaspalg.com\/fr\/wp-json\/wp\/v2\/comments?post=5508"}],"version-history":[{"count":2,"href":"https:\/\/aquaspalg.com\/fr\/wp-json\/wp\/v2\/pages\/5508\/revisions"}],"predecessor-version":[{"id":6372,"href":"https:\/\/aquaspalg.com\/fr\/wp-json\/wp\/v2\/pages\/5508\/revisions\/6372"}],"up":[{"embeddable":true,"href":"https:\/\/aquaspalg.com\/fr\/wp-json\/wp\/v2\/pages\/1033"}],"wp:attachment":[{"href":"https:\/\/aquaspalg.com\/fr\/wp-json\/wp\/v2\/media?parent=5508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}